{"id":1624,"date":"2025-02-21T19:30:24","date_gmt":"2025-02-21T19:30:24","guid":{"rendered":"https:\/\/99bitcoins.com\/br\/?p=1624"},"modified":"2025-02-21T19:30:24","modified_gmt":"2025-02-21T19:30:24","slug":"drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital","status":"publish","type":"post","link":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\/","title":{"rendered":"Drex: conhe\u00e7a os projetos selecionados na segunda fase de testes da moeda digital"},"content":{"rendered":"<p>O Drex se prepara para dar in\u00edcio a segunda fase de testes com o piloto da moeda digital. De acordo com o Banco Central, a pr\u00f3xima etapa de avalia\u00e7\u00e3o da CBDC brasileira deve terminar no final do primeiro semestre de 2025.<\/p>\n<p>Os primeiros testes com o Piloto Drex tiveram in\u00edcio em abril de 2023, ap\u00f3s o Banco Central selecionar 16 propostas de implanta\u00e7\u00e3o de neg\u00f3cios para a CBDC. No total, 36 propostas foram inscritas na primeira sele\u00e7\u00e3o do programa.<\/p>\n<p>Nessa etapa de avalia\u00e7\u00e3o dos projetos, cons\u00f3rcios formados por institui\u00e7\u00f5es financeiras foram escolhidos para testar a moeda digital, incluindo, por exemplo, empresas como Banco do Brasil, Mercado Bitcoin e B3.<\/p>\n<h2>Segunda fase com o piloto Drex<\/h2>\n<p>Em parceria com a Comiss\u00e3o de Valores Mobili\u00e1rios (CVM), o Banco Central anunciou uma nova lista de selecionados para a fase de testes com o Drex.<\/p>\n<p>A divulga\u00e7\u00e3o, realizada no final de 2024, contempla 13 institui\u00e7\u00f5es financeiras com novas ades\u00f5es, assim como alguns participantes da primeira fase.<\/p>\n<p>No total, a segunda fase de testes com a CDBC brasileira recebeu 42 propostas. Os projetos selecionados representam iniciativas como:<\/p>\n<h3>. ABC e Inter<\/h3>\n<p>Em nova parceria durante a segunda fase do Drex, o ABC e o banco Inter integram a tecnologia de registro distribu\u00edda em uma simula\u00e7\u00e3o de concess\u00e3o de receb\u00edveis de cart\u00f5es de cr\u00e9dito. Em suma, o objetivo da proposta selecionada \u00e9 facilitar a oferta de cr\u00e9ditos para pequenas empresas.<\/p>\n<h3>. Banco do Brasil, Bradesco e Ita\u00fa<\/h3>\n<p>Os tr\u00eas bancos se uniram em um cons\u00f3rcio com foco em cr\u00e9dito colaterizado em Certificados de Dep\u00f3sito Banc\u00e1rio (CBDs). Desse modo, o Drex ser\u00e1 inserido em opera\u00e7\u00f5es de capital de giro para empresas. O projeto prev\u00ea, ainda, a contra\u00e7\u00e3o de empr\u00e9stimos que possuem como garantia esses certificados.<\/p>\n<h3>. ABBC, ABC e Mercado Bitcoin<\/h3>\n<p>Dessa vez, o cons\u00f3rcio entre as tr\u00eas institui\u00e7\u00f5es financeiras visa estimular o uso de t\u00edtulos p\u00fablicos por usu\u00e1rios de poupan\u00e7as no Brasil. A ideia, portanto, segue a mesma finalidade da primeira etapa. Por\u00e9m, pretende usar a poupan\u00e7a como colateraliza\u00e7\u00e3o em empr\u00e9stimos simulados com o Drex.<\/p>\n<h3>. Inter<\/h3>\n<p>O banco Inter apresentou um projeto envolvendo Trade Marketing e a CBDC brasileira. Desse modo, a institui\u00e7\u00e3o anseia pelo uso da moeda digital em negocia\u00e7\u00e3o de commodities. O projeto deve usar, ainda, a tokeniza\u00e7\u00e3o de ativos no processo de embarque e fiscaliza\u00e7\u00e3o de mercadorias exportadas pelo Brasil.<\/p>\n<h3>. XP, Visa e Nubank<\/h3>\n<p>As tr\u00eas empresas se uniram para otimizar o mercado de c\u00e2mbio atrav\u00e9s do Drex. A proposta selecionada pelo Banco Central pode apresentar redu\u00e7\u00e3o de custos para a atividade, assim como testar a disponibilidade de um mercado de negocia\u00e7\u00e3o ininterrupto.<\/p>\n<h3>. ABC, Inter e MB<\/h3>\n<p>Esse cons\u00f3rcio espera criar um pool de liquidez para t\u00edtulos p\u00fablicos com o real digital. Nesse sentido, a ideia resulta de inspira\u00e7\u00e3o em projetos de finan\u00e7as descentralizadas (DeFi), integrando contratos inteligentes em opera\u00e7\u00f5es com t\u00edtulos p\u00fablicos brasileiros.<\/p>\n<h3>. ABBC<\/h3>\n<p>A segunda fase do piloto Drex\u00a0 aprovou, tamb\u00e9m, uma proposta defendida pelo ABBC com foco em transa\u00e7\u00f5es com c\u00e9dulas de cr\u00e9dito banc\u00e1rio e o Drex.<\/p>\n<h3>. B3, BTG e Santander<\/h3>\n<p>As institui\u00e7\u00f5es B3, BTG e Santander comp\u00f5em um grupo centrado em testes com transa\u00e7\u00f5es entre deb\u00eantures e a CBDC brasileira. Em s\u00edntese, a ideia \u00e9 reduzir os custos operacionais desse mercado, descomplicando transa\u00e7\u00f5es, bem como ampliando a liquidez e a negocia\u00e7\u00e3o desses t\u00edtulos.<\/p>\n<h3>. TecBan, Mercado Bitcoin, XP e Visa<\/h3>\n<p>Com o prosseguimento dos testes do piloto Drex, as empresas TecBan, Mercado Bitcoin, XP e Visa estudam, agora, alternativas de negocia\u00e7\u00e3o de ativos de valor produzidos pelo agroneg\u00f3cio.<\/p>\n<h3>. Santander<\/h3>\n<p>Mais uma proposta envolvendo o Santander participar\u00e1 dessa nova fase de testes. O projeto inscrito pelo banco espanhol prev\u00ea a negocia\u00e7\u00e3o de cr\u00e9ditos de descarboniza\u00e7\u00e3o (CBIO) em opera\u00e7\u00f5es simuladas com o Drex. O objetivo, em suma, \u00e9 promover atividades sustent\u00e1veis em setores como o agroneg\u00f3cio no Brasil.<\/p>\n<h3>. B3, BV e Santander<\/h3>\n<p>O Santander integrou o cons\u00f3rcio com as institui\u00e7\u00f5es financeiras B3 e o banco BV para dar continuidade ao projeto com o Drex voltado para a transfer\u00eancia de autom\u00f3veis.<\/p>\n<h3>. Mercado Bitcoin<\/h3>\n<p>A exchange brasileira Mercado Bitcoin teve uma proposta aprovada que envolve o uso da CBDC brasileira em redes blockchains p\u00fablicas. A ideia \u00e9 criar novos modelos de neg\u00f3cio e inclus\u00e3o financeira a partir dessa integra\u00e7\u00e3o.<\/p>\n<h3>. BB, Caixa e SFCoop<\/h3>\n<p>O Banco do Brasil, a Caixa e a SFCoop se uniram para criar um ecossistema digital para a transfer\u00eancia e negocia\u00e7\u00e3o de im\u00f3veis. O uso do Drex traz mais facilidade e seguran\u00e7a para esse tipo de opera\u00e7\u00e3o, que envolve transfer\u00eancias de titularidade de im\u00f3veis e transa\u00e7\u00f5es com alto volume.<\/p>\n<h2>Drex ser\u00e1 lan\u00e7ado oficialmente em 2025?<\/h2>\n<p>A segunda etapa de testes do Piloto Drex deve finalizar o per\u00edodo de avalia\u00e7\u00e3o do projeto. Desde 2023, o Banco Central experimenta solu\u00e7\u00f5es baseadas na CBDC brasileira, incluindo experimentos de execu\u00e7\u00e3o de contratos inteligentes.<\/p>\n<p>Depois de ser adiada em 2024, o Drex pode ser finalmente lan\u00e7ado neste ano. A expectativa do Banco Central \u00e9 liberar de forma gradativa a integra\u00e7\u00e3o da moeda digital com o Sistema Financeiro Nacional at\u00e9 o final de 2025.<\/p>\n<p>No entanto, o pr\u00f3prio BC admite que pode o <a class=\"general-link\" href=\"https:\/\/99bitcoins.com\/br\/noticias\/altcoin\/lancamento-drex-criptomoeda-do-banco-central\/\" target=\"_blank\" rel=\"noopener\">lan\u00e7amento oficial deve ficar para o ano seguinte.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Drex se prepara para dar in\u00edcio a segunda fase de testes com o piloto da moeda digital. De acordo com o Banco Central, a pr\u00f3xima etapa de avalia\u00e7\u00e3o da CBDC brasileira deve terminar no final do primeiro semestre de 2025. Os primeiros testes com o Piloto Drex tiveram in\u00edcio em abril de 2023, ap\u00f3s..<\/p>\n","protected":false},"author":136019,"featured_media":1630,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[7],"tags":[50,162,47,130,131],"coin":[132],"class_list":["post-1624","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado","tag-cbdc","tag-cbdc-brasileira","tag-drex","tag-lancamento-drex","tag-testes-drex"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Drex: conhe\u00e7a os projetos selecionados na segunda fase de testes - 99Bitcoins Brasil<\/title>\n<meta name=\"description\" content=\"Drex se prepara para dar in\u00edcio a segunda fase de testes com o piloto da moeda digital. Conhe\u00e7a os projetos que fazem parte desta etapa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Drex: conhe\u00e7a os projetos selecionados na segunda fase de testes - 99Bitcoins Brasil\" \/>\n<meta property=\"og:description\" content=\"Drex se prepara para dar in\u00edcio a segunda fase de testes com o piloto da moeda digital. Conhe\u00e7a os projetos que fazem parte desta etapa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\/\" \/>\n<meta property=\"og:site_name\" content=\"99Bitcoins Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-21T19:30:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/02\/DREX-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1204\" \/>\n\t<meta property=\"og:image:height\" content=\"803\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mariana Eberhard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mariana Eberhard\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\\\/\"},\"author\":{\"name\":\"Mariana Eberhard\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#\\\/schema\\\/person\\\/73cb6b545727b00e0383b76ba1393194\"},\"headline\":\"Drex: conhe\u00e7a os projetos selecionados na segunda fase de testes da moeda digital\",\"datePublished\":\"2025-02-21T19:30:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\\\/\"},\"wordCount\":944,\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/02\\\/DREX-2.png\",\"keywords\":[\"CBDC\",\"CBDC brasileira\",\"Drex\",\"Lan\u00e7amento Drex\",\"Testes Drex\"],\"articleSection\":[\"Not\u00edcias do Mercado\"],\"inLanguage\":\"pt-BR\",\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\\\/\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\\\/\",\"name\":\"Drex: conhe\u00e7a os projetos selecionados na segunda fase de testes - 99Bitcoins Brasil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/02\\\/DREX-2.png\",\"datePublished\":\"2025-02-21T19:30:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#\\\/schema\\\/person\\\/73cb6b545727b00e0383b76ba1393194\"},\"description\":\"Drex se prepara para dar in\u00edcio a segunda fase de testes com o piloto da moeda digital. Conhe\u00e7a os projetos que fazem parte desta etapa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\\\/#primaryimage\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/02\\\/DREX-2.png\",\"contentUrl\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/02\\\/DREX-2.png\",\"width\":1204,\"height\":803,\"caption\":\"Reprodu\u00e7\u00e3o: IA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Not\u00edcias do Mercado\",\"item\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/noticias\\\/mercado\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Drex: conhe\u00e7a os projetos selecionados na segunda fase de testes da moeda digital\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#website\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/\",\"name\":\"99Bitcoins Brasil\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/#\\\/schema\\\/person\\\/73cb6b545727b00e0383b76ba1393194\",\"name\":\"Mariana Eberhard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f8c7385de1d5e30d801bad166eed5375532cf43687eb42cfb96ccce31c1dcf4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f8c7385de1d5e30d801bad166eed5375532cf43687eb42cfb96ccce31c1dcf4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f8c7385de1d5e30d801bad166eed5375532cf43687eb42cfb96ccce31c1dcf4?s=96&d=mm&r=g\",\"caption\":\"Mariana Eberhard\"},\"description\":\"Gerente de Marketing do 99Bitcoins Brasil, Mariana trabalha com conte\u00fado sobre criptomoedas e Bitcoin h\u00e1 3 anos.\",\"url\":\"https:\\\/\\\/99bitcoins.com\\\/br\\\/author\\\/br\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Drex: conhe\u00e7a os projetos selecionados na segunda fase de testes - 99Bitcoins Brasil","description":"Drex se prepara para dar in\u00edcio a segunda fase de testes com o piloto da moeda digital. Conhe\u00e7a os projetos que fazem parte desta etapa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\/","og_locale":"pt_BR","og_type":"article","og_title":"Drex: conhe\u00e7a os projetos selecionados na segunda fase de testes - 99Bitcoins Brasil","og_description":"Drex se prepara para dar in\u00edcio a segunda fase de testes com o piloto da moeda digital. Conhe\u00e7a os projetos que fazem parte desta etapa.","og_url":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\/","og_site_name":"99Bitcoins Brasil","article_published_time":"2025-02-21T19:30:24+00:00","og_image":[{"width":1204,"height":803,"url":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/02\/DREX-2.png","type":"image\/png"}],"author":"Mariana Eberhard","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Mariana Eberhard","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\/#article","isPartOf":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\/"},"author":{"name":"Mariana Eberhard","@id":"https:\/\/99bitcoins.com\/br\/#\/schema\/person\/73cb6b545727b00e0383b76ba1393194"},"headline":"Drex: conhe\u00e7a os projetos selecionados na segunda fase de testes da moeda digital","datePublished":"2025-02-21T19:30:24+00:00","mainEntityOfPage":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\/"},"wordCount":944,"image":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/02\/DREX-2.png","keywords":["CBDC","CBDC brasileira","Drex","Lan\u00e7amento Drex","Testes Drex"],"articleSection":["Not\u00edcias do Mercado"],"inLanguage":"pt-BR","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/99bitcoins.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\/","url":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\/","name":"Drex: conhe\u00e7a os projetos selecionados na segunda fase de testes - 99Bitcoins Brasil","isPartOf":{"@id":"https:\/\/99bitcoins.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\/#primaryimage"},"image":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\/#primaryimage"},"thumbnailUrl":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/02\/DREX-2.png","datePublished":"2025-02-21T19:30:24+00:00","author":{"@id":"https:\/\/99bitcoins.com\/br\/#\/schema\/person\/73cb6b545727b00e0383b76ba1393194"},"description":"Drex se prepara para dar in\u00edcio a segunda fase de testes com o piloto da moeda digital. Conhe\u00e7a os projetos que fazem parte desta etapa.","breadcrumb":{"@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/99bitcoins.com\/br\/noticias\/mercado\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\/#primaryimage","url":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/02\/DREX-2.png","contentUrl":"https:\/\/99bitcoins.com\/br\/wp-content\/uploads\/sites\/11\/2025\/02\/DREX-2.png","width":1204,"height":803,"caption":"Reprodu\u00e7\u00e3o: IA"},{"@type":"BreadcrumbList","@id":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/drex-conheca-os-projetos-selecionados-na-segunda-fase-de-testes-da-moeda-digital\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/99bitcoins.com\/br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/99bitcoins.com\/br\/noticias\/"},{"@type":"ListItem","position":3,"name":"Not\u00edcias do Mercado","item":"https:\/\/99bitcoins.com\/br\/noticias\/mercado\/"},{"@type":"ListItem","position":4,"name":"Drex: conhe\u00e7a os projetos selecionados na segunda fase de testes da moeda digital"}]},{"@type":"WebSite","@id":"https:\/\/99bitcoins.com\/br\/#website","url":"https:\/\/99bitcoins.com\/br\/","name":"99Bitcoins Brasil","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/99bitcoins.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/99bitcoins.com\/br\/#\/schema\/person\/73cb6b545727b00e0383b76ba1393194","name":"Mariana Eberhard","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9f8c7385de1d5e30d801bad166eed5375532cf43687eb42cfb96ccce31c1dcf4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9f8c7385de1d5e30d801bad166eed5375532cf43687eb42cfb96ccce31c1dcf4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9f8c7385de1d5e30d801bad166eed5375532cf43687eb42cfb96ccce31c1dcf4?s=96&d=mm&r=g","caption":"Mariana Eberhard"},"description":"Gerente de Marketing do 99Bitcoins Brasil, Mariana trabalha com conte\u00fado sobre criptomoedas e Bitcoin h\u00e1 3 anos.","url":"https:\/\/99bitcoins.com\/br\/author\/br\/"}]}},"_links":{"self":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts\/1624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/users\/136019"}],"replies":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/comments?post=1624"}],"version-history":[{"count":5,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts\/1624\/revisions"}],"predecessor-version":[{"id":39196,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/posts\/1624\/revisions\/39196"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/media\/1630"}],"wp:attachment":[{"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/media?parent=1624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/categories?post=1624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/tags?post=1624"},{"taxonomy":"coin","embeddable":true,"href":"https:\/\/99bitcoins.com\/br\/wp-json\/wp\/v2\/coin?post=1624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}